{"id":9349,"date":"2025-07-21T11:38:05","date_gmt":"2025-07-21T09:38:05","guid":{"rendered":"https:\/\/ariva.ag\/glossary\/dividende\/"},"modified":"2025-07-21T11:38:05","modified_gmt":"2025-07-21T09:38:05","slug":"dividende","status":"publish","type":"glossary","link":"https:\/\/ariva.ag\/en\/glossary\/dividende\/","title":{"rendered":"Dividende"},"content":{"rendered":"<p>&#8220;Eine Dividende ist eine gewinnabh\u00e4ngige Zahlung eines Unternehmens an seine Anteilseigner. Durch die Dividende beteiligt das Unternehmen seine Aktion\u00e4re am Erfolg und entlohnt sie f\u00fcr ihre Kapitaleinlage. Die H\u00f6he der Dividende wird j\u00e4hrlich von der Hauptversammlung (HV) einer Aktiengesellschaft festgelegt und entweder als Euro-Betrag oder als prozentualer Anteil am Unternehmensgewinn angegeben. Der B\u00f6rsenkurs wird nach dem HV-Beschluss um die H\u00f6he der Dividende vermindert und der erste Preis ohne Dividende mit \u201eex Dividende\u201c gekennzeichnet. Erwerber einer Aktie ex Dividende haben keinen Anspruch auf diese Dividende.\u00a0 Die Dividende ist f\u00fcr alle Aktien eines Unternehmens derselben Gattung (z. B. Stammaktie oder Vorzugsaktie) gleich hoch. Sie richtet sich in erster Linie nach dem Bilanzgewinn und der wirtschaftlichen Perspektive des Unternehmens und wird der HV vom Vorstand und Aufsichtsrat vorgeschlagen. Unternehmen streben h\u00e4ufig eine konstante Dividendenzahlung an, um in ertragsschwachen Phasen eine positive Ertragserwartung zu vermitteln. Ausgezahlt wird die Dividende durch die f\u00fcr das Unternehmen t\u00e4tigen Banken. Die vor Abzug der Unternehmenssteuer bezeichnet man als Bruttodividende, die nach Abzug als Bardividende und die nach Abzug der Abgeltungssteuer als Nettodividende.\u00a0&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Eine Dividende ist eine gewinnabh\u00e4ngige Zahlung eines Unternehmens an seine Anteilseigner. Durch die Dividende beteiligt das Unternehmen seine Aktion\u00e4re am Erfolg und entlohnt sie f\u00fcr ihre Kapitaleinlage. Die H\u00f6he der Dividende wird j\u00e4hrlich von der Hauptversammlung (HV) einer Aktiengesellschaft festgelegt und entweder als Euro-Betrag oder als prozentualer Anteil am Unternehmensgewinn angegeben. Der B\u00f6rsenkurs wird nach [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"menu_order":0,"template":"","meta":{"content-type":"","footnotes":""},"glossary-categories":[],"glossary-tags":[],"class_list":["post-9349","glossary","type-glossary","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dividende - ARIVA: Finanzdaten sind unser Business<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ariva.ag\/glossary\/dividende\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dividende\" \/>\n<meta property=\"og:description\" content=\"&#8220;Eine Dividende ist eine gewinnabh\u00e4ngige Zahlung eines Unternehmens an seine Anteilseigner. Durch die Dividende beteiligt das Unternehmen seine Aktion\u00e4re am Erfolg und entlohnt sie f\u00fcr ihre Kapitaleinlage. Die H\u00f6he der Dividende wird j\u00e4hrlich von der Hauptversammlung (HV) einer Aktiengesellschaft festgelegt und entweder als Euro-Betrag oder als prozentualer Anteil am Unternehmensgewinn angegeben. Der B\u00f6rsenkurs wird nach [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ariva.ag\/en\/glossary\/dividende\/\" \/>\n<meta property=\"og:site_name\" content=\"ARIVA: Finanzdaten sind unser Business\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ariva.ag\\\/glossary\\\/dividende\\\/\",\"url\":\"https:\\\/\\\/ariva.ag\\\/glossary\\\/dividende\\\/\",\"name\":\"Dividende - ARIVA: Finanzdaten sind unser Business\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ariva.ag\\\/#website\"},\"datePublished\":\"2025-07-21T09:38:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ariva.ag\\\/glossary\\\/dividende\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ariva.ag\\\/glossary\\\/dividende\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ariva.ag\\\/glossary\\\/dividende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ariva.ag\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dividende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ariva.ag\\\/#website\",\"url\":\"https:\\\/\\\/ariva.ag\\\/\",\"name\":\"ARIVA.AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ariva.ag\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ariva.ag\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ariva.ag\\\/#organization\",\"name\":\"ARIVA: Finanzdaten sind unser Business\",\"url\":\"https:\\\/\\\/ariva.ag\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ariva.ag\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ariva.ag\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Ariva-AG-Logo.png\",\"contentUrl\":\"https:\\\/\\\/ariva.ag\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Ariva-AG-Logo.png\",\"width\":295,\"height\":88,\"caption\":\"ARIVA: Finanzdaten sind unser Business\"},\"image\":{\"@id\":\"https:\\\/\\\/ariva.ag\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de.linkedin.com\\\/company\\\/ariva-de-ag\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dividende - ARIVA: Finanzdaten sind unser Business","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ariva.ag\/glossary\/dividende\/","og_locale":"en_US","og_type":"article","og_title":"Dividende","og_description":"&#8220;Eine Dividende ist eine gewinnabh\u00e4ngige Zahlung eines Unternehmens an seine Anteilseigner. Durch die Dividende beteiligt das Unternehmen seine Aktion\u00e4re am Erfolg und entlohnt sie f\u00fcr ihre Kapitaleinlage. Die H\u00f6he der Dividende wird j\u00e4hrlich von der Hauptversammlung (HV) einer Aktiengesellschaft festgelegt und entweder als Euro-Betrag oder als prozentualer Anteil am Unternehmensgewinn angegeben. Der B\u00f6rsenkurs wird nach [&hellip;]","og_url":"https:\/\/ariva.ag\/en\/glossary\/dividende\/","og_site_name":"ARIVA: Finanzdaten sind unser Business","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ariva.ag\/glossary\/dividende\/","url":"https:\/\/ariva.ag\/glossary\/dividende\/","name":"Dividende - ARIVA: Finanzdaten sind unser Business","isPartOf":{"@id":"https:\/\/ariva.ag\/#website"},"datePublished":"2025-07-21T09:38:05+00:00","breadcrumb":{"@id":"https:\/\/ariva.ag\/glossary\/dividende\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ariva.ag\/glossary\/dividende\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ariva.ag\/glossary\/dividende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ariva.ag\/"},{"@type":"ListItem","position":2,"name":"Dividende"}]},{"@type":"WebSite","@id":"https:\/\/ariva.ag\/#website","url":"https:\/\/ariva.ag\/","name":"ARIVA.AG","description":"","publisher":{"@id":"https:\/\/ariva.ag\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ariva.ag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ariva.ag\/#organization","name":"ARIVA: Finanzdaten sind unser Business","url":"https:\/\/ariva.ag\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ariva.ag\/#\/schema\/logo\/image\/","url":"https:\/\/ariva.ag\/wp-content\/uploads\/2024\/08\/Ariva-AG-Logo.png","contentUrl":"https:\/\/ariva.ag\/wp-content\/uploads\/2024\/08\/Ariva-AG-Logo.png","width":295,"height":88,"caption":"ARIVA: Finanzdaten sind unser Business"},"image":{"@id":"https:\/\/ariva.ag\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de.linkedin.com\/company\/ariva-de-ag"]}]}},"_links":{"self":[{"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/glossary\/9349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/glossary\/9349\/revisions"}],"wp:attachment":[{"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/media?parent=9349"}],"wp:term":[{"taxonomy":"glossary-categories","embeddable":true,"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/glossary-categories?post=9349"},{"taxonomy":"glossary-tags","embeddable":true,"href":"https:\/\/ariva.ag\/en\/wp-json\/wp\/v2\/glossary-tags?post=9349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}